{"id":1754,"date":"2021-11-25T20:36:32","date_gmt":"2021-11-25T20:36:32","guid":{"rendered":"https:\/\/instantpadel.eu\/?page_id=1754"},"modified":"2021-11-26T15:57:06","modified_gmt":"2021-11-26T15:57:06","slug":"sol","status":"publish","type":"page","link":"https:\/\/instantcourts.com\/instantpadel\/fr\/sol\/","title":{"rendered":"Sol"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1754\" class=\"elementor elementor-1754\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-25e8c42d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"25e8c42d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-39dfd3ce\" data-id=\"39dfd3ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c12521 elementor-widget elementor-widget-heading\" data-id=\"6c12521\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Joue parfaitement au padel sur un sol dur. Excellent rebond de la balle et adh\u00e9rence parfaite<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14cf7d2b elementor-widget elementor-widget-text-editor\" data-id=\"14cf7d2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p><p>La qualit\u00e9 et la durabilit\u00e9 sont des facteurs d\u00e9cisifs dans le choix d&#8217;Instantpadel pour ce rev\u00eatement de terrain dur. Les panneaux sportifs modulaires sont r\u00e9sistants \u00e0 la d\u00e9coloration, \u00e0 l&#8217;humidit\u00e9, \u00e0 la formation de moisissures et aux bact\u00e9ries. Le froid, la chaleur et les variations extr\u00eames de temp\u00e9rature n&#8217;ont \u00e9galement aucune influence sur eux. La surface est r\u00e9sistante aux UV et antistatique. La couche sup\u00e9rieure sp\u00e9ciale assure un s\u00e9chage rapide de la surface, quelle que soit l&#8217;intensit\u00e9 de l&#8217;averse.<\/p><p>Les panneaux en plastique dur peuvent supporter une utilisation extr\u00eame du court.<\/p><p>Le sol, qui mesure 200 m\u00b2, est un sol en plastique portable. Il est livr\u00e9 par la soci\u00e9t\u00e9 VersaCourt, leader mondial dans ce domaine. Le sol est approuv\u00e9 pour les comp\u00e9titions internationales par, entre autres, la F\u00e9d\u00e9ration internationale de tennis.<\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e13b70d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e13b70d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c030846\" data-id=\"c030846\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbe0af6 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"cbe0af6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">CONCEPTION S\u00dbRE, ABSORBANT LES CHOCS<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">FACILE \u00c0 ENTRETENIR<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-90f3921\" data-id=\"90f3921\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b727948 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b727948\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">DURABILIT\u00c9 EXCEPTIONNELLE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">ASPECT ATTRAYANT<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3fa580d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3fa580d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9814f27\" data-id=\"9814f27\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c82ba7d elementor-widget elementor-widget-image\" data-id=\"c82ba7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"660\" height=\"336\" src=\"https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/2021\/11\/game-combo.png\" class=\"attachment-large size-large wp-image-1517\" alt=\"\" srcset=\"https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/2021\/11\/game-combo.png 660w, https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/2021\/11\/game-combo-300x153.png 300w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-26efd79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"26efd79\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3267b97\" data-id=\"3267b97\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5502747 elementor-widget elementor-widget-heading\" data-id=\"5502747\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Caract\u00e9ristiques<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-697eb6a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"697eb6a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d42e7f4\" data-id=\"d42e7f4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32a251f elementor-widget elementor-widget-accordion\" data-id=\"32a251f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5301\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-5301\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Mat\u00e9riau r\u00e9silient<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-5301\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-5301\"><p>Les dalles VersaCourt sont moul\u00e9es \u00e0 partir d&#8217;un m\u00e9lange sp\u00e9cial de polypropyl\u00e8ne copolym\u00e8re \u00e0 haute r\u00e9sistance aux chocs qui les prot\u00e8ge contre les fractures lors de jeux intensifs, tandis qu&#8217;un stabilisateur UV et des additifs antioxydants sont inclus pour emp\u00eacher la d\u00e9coloration et la d\u00e9t\u00e9rioration des dalles.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5302\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-5302\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">M\u00e9canisme de verrouillage de pr\u00e9cision<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-5302\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-5302\"><p>Notre m\u00e9canisme d&#8217;embo\u00eetement r\u00e9volutionnaire utilise six points de verrouillage sur chaque dalle. Ces six points de verrouillage distincts s&#8217;embo\u00eetent facilement et maintiennent la dalle \u00e0 plat, emp\u00eachant toute dalle de tourner ou de se recroqueviller.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5303\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-5303\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Taille optimale des dalles<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-5303\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-5303\"><p>Des travaux de recherche et de d\u00e9veloppement approfondis ont permis de d\u00e9couvrir que la taille optimale des dalles pour des performances optimales est de 10&#8243; x 10&#8243;. La conception innovante de VersaCourt offre l&#8217;une des surfaces de jeu les plus r\u00e9guli\u00e8res du march\u00e9, permettant une r\u00e9ponse incroyable de la balle et une jouabilit\u00e9 in\u00e9gal\u00e9e.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5304\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-5304\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Protection pour les athl\u00e8tes<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-5304\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-5304\"><p>Des joints de dilatation \u00e0 tension de ressort invers\u00e9e et un m\u00e9canisme d&#8217;accrochage \u00e0 ressort permettent un l\u00e9ger mouvement lat\u00e9ral entre les dalles. Ce mouvement, associ\u00e9 \u00e0 une l\u00e9g\u00e8re flexion verticale, permet de m\u00e9nager les lombaires, les genoux et les articulations des joueurs.<\/p><p>.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9160ec8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9160ec8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b0fcc7f\" data-id=\"b0fcc7f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75c9e22 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"75c9e22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-shield-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGarantie de 5 ans\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLes terrains Game Outdoor sont couverts par notre garantie de cinq ans, assurant aux clients de VersaCourt des terrains dont ils pourront profiter pendant des d\u00e9cennies.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b8b8866\" data-id=\"b8b8866\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a010c5 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3a010c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-edit\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tOptions personnalisables\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLes syst\u00e8mes VersaCourt peuvent \u00eatre configur\u00e9s avec un large \u00e9ventail de couleurs de dalles diff\u00e9rentes, ainsi que des lignes de jeu, des logos et des graphiques personnalisables. Des options de couleurs personnalis\u00e9es sont \u00e9galement disponibles sur demande.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-55554ad\" data-id=\"55554ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee64ae4 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"ee64ae4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-expand-arrows-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tConception de la grille ouverte\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLes flaques d'eau ne sont plus un probl\u00e8me. Nos tuiles sont fabriqu\u00e9es avec une grille ouverte qui permet \u00e0 la piste de se drainer et de s\u00e9cher rapidement.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Joue parfaitement au padel sur un sol dur. Excellent rebond de la balle et adh\u00e9rence parfaite La qualit\u00e9 et la durabilit\u00e9 sont des facteurs d\u00e9cisifs dans le choix d&#8217;Instantpadel pour ce rev\u00eatement de terrain dur. Les panneaux sportifs modulaires sont r\u00e9sistants \u00e0 la d\u00e9coloration, \u00e0 l&#8217;humidit\u00e9, \u00e0 la formation de moisissures et aux bact\u00e9ries. Le [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":971,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1754","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sol - Instantpadel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/instantcourts.com\/instantpadel\/fr\/sol\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sol - Instantpadel\" \/>\n<meta property=\"og:description\" content=\"Joue parfaitement au padel sur un sol dur. Excellent rebond de la balle et adh\u00e9rence parfaite La qualit\u00e9 et la durabilit\u00e9 sont des facteurs d\u00e9cisifs dans le choix d&#8217;Instantpadel pour ce rev\u00eatement de terrain dur. Les panneaux sportifs modulaires sont r\u00e9sistants \u00e0 la d\u00e9coloration, \u00e0 l&#8217;humidit\u00e9, \u00e0 la formation de moisissures et aux bact\u00e9ries. Le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/instantcourts.com\/instantpadel\/fr\/sol\/\" \/>\n<meta property=\"og:site_name\" content=\"Instantpadel\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Instantpadel\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-26T15:57:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/2021\/10\/29.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1439\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/fr\\\/sol\\\/\",\"url\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/fr\\\/sol\\\/\",\"name\":\"Sol - Instantpadel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/fr\\\/sol\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/fr\\\/sol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/29.jpg\",\"datePublished\":\"2021-11-25T20:36:32+00:00\",\"dateModified\":\"2021-11-26T15:57:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/fr\\\/sol\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/fr\\\/sol\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/fr\\\/sol\\\/#primaryimage\",\"url\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/29.jpg\",\"contentUrl\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/29.jpg\",\"width\":1920,\"height\":1439},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/fr\\\/sol\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sol\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/#website\",\"url\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/\",\"name\":\"Instantpadel\",\"description\":\"Padel Courts the clever way\",\"publisher\":{\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/#organization\",\"name\":\"Instantpadel\",\"url\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/Instantpadel.webp\",\"contentUrl\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/Instantpadel.webp\",\"width\":2048,\"height\":2048,\"caption\":\"Instantpadel\"},\"image\":{\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Instantpadel\\\/\",\"https:\\\/\\\/www.instagram.com\\\/instantpadel.eu\\\/\",\"https:\\\/\\\/in.linkedin.com\\\/company\\\/instantpadel\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sol - Instantpadel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/instantcourts.com\/instantpadel\/fr\/sol\/","og_locale":"en_US","og_type":"article","og_title":"Sol - Instantpadel","og_description":"Joue parfaitement au padel sur un sol dur. Excellent rebond de la balle et adh\u00e9rence parfaite La qualit\u00e9 et la durabilit\u00e9 sont des facteurs d\u00e9cisifs dans le choix d&#8217;Instantpadel pour ce rev\u00eatement de terrain dur. Les panneaux sportifs modulaires sont r\u00e9sistants \u00e0 la d\u00e9coloration, \u00e0 l&#8217;humidit\u00e9, \u00e0 la formation de moisissures et aux bact\u00e9ries. Le [&hellip;]","og_url":"https:\/\/instantcourts.com\/instantpadel\/fr\/sol\/","og_site_name":"Instantpadel","article_publisher":"https:\/\/www.facebook.com\/Instantpadel\/","article_modified_time":"2021-11-26T15:57:06+00:00","og_image":[{"width":1920,"height":1439,"url":"https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/2021\/10\/29.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/instantcourts.com\/instantpadel\/fr\/sol\/","url":"https:\/\/instantcourts.com\/instantpadel\/fr\/sol\/","name":"Sol - Instantpadel","isPartOf":{"@id":"https:\/\/instantcourts.com\/instantpadel\/#website"},"primaryImageOfPage":{"@id":"https:\/\/instantcourts.com\/instantpadel\/fr\/sol\/#primaryimage"},"image":{"@id":"https:\/\/instantcourts.com\/instantpadel\/fr\/sol\/#primaryimage"},"thumbnailUrl":"https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/2021\/10\/29.jpg","datePublished":"2021-11-25T20:36:32+00:00","dateModified":"2021-11-26T15:57:06+00:00","breadcrumb":{"@id":"https:\/\/instantcourts.com\/instantpadel\/fr\/sol\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/instantcourts.com\/instantpadel\/fr\/sol\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/instantcourts.com\/instantpadel\/fr\/sol\/#primaryimage","url":"https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/2021\/10\/29.jpg","contentUrl":"https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/2021\/10\/29.jpg","width":1920,"height":1439},{"@type":"BreadcrumbList","@id":"https:\/\/instantcourts.com\/instantpadel\/fr\/sol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/instantcourts.com\/instantpadel\/"},{"@type":"ListItem","position":2,"name":"Sol"}]},{"@type":"WebSite","@id":"https:\/\/instantcourts.com\/instantpadel\/#website","url":"https:\/\/instantcourts.com\/instantpadel\/","name":"Instantpadel","description":"Padel Courts the clever way","publisher":{"@id":"https:\/\/instantcourts.com\/instantpadel\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/instantcourts.com\/instantpadel\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/instantcourts.com\/instantpadel\/#organization","name":"Instantpadel","url":"https:\/\/instantcourts.com\/instantpadel\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/instantcourts.com\/instantpadel\/#\/schema\/logo\/image\/","url":"https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/Instantpadel.webp","contentUrl":"https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/Instantpadel.webp","width":2048,"height":2048,"caption":"Instantpadel"},"image":{"@id":"https:\/\/instantcourts.com\/instantpadel\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Instantpadel\/","https:\/\/www.instagram.com\/instantpadel.eu\/","https:\/\/in.linkedin.com\/company\/instantpadel"]}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/pages\/1754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/comments?post=1754"}],"version-history":[{"count":0,"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/pages\/1754\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/media\/971"}],"wp:attachment":[{"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/media?parent=1754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}