{"id":8105,"date":"2023-10-31T11:39:35","date_gmt":"2023-10-31T11:39:35","guid":{"rendered":"https:\/\/instantpadel.eu\/?p=8105"},"modified":"2023-10-31T11:39:52","modified_gmt":"2023-10-31T11:39:52","slug":"central-london-alliance-2","status":"publish","type":"post","link":"https:\/\/instantcourts.com\/instantpadel\/nl\/central-london-alliance-2\/","title":{"rendered":"Central London Alliance"},"content":{"rendered":"\n<p>1 Niet overdekt Instantpadelveld<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1536\" height=\"2048\" data-id=\"8100\" src=\"https:\/\/instantpadel.eu\/wp-content\/uploads\/sites\/2\/Central-London-Alliance.jpg\" alt=\"Central London Alliance\" class=\"wp-image-8100\" srcset=\"https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/Central-London-Alliance.jpg 1536w, https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/Central-London-Alliance-225x300.jpg 225w, https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/Central-London-Alliance-768x1024.jpg 768w, https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/Central-London-Alliance-1152x1536.jpg 1152w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>1 Niet overdekt Instantpadelveld<\/p>\n","protected":false},"author":4,"featured_media":8101,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[111],"tags":[136],"class_list":["post-8105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casestudies","tag-verenigd-koninkrijk"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Central London Alliance - Instantpadel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/instantcourts.com\/instantpadel\/nl\/central-london-alliance-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Central London Alliance - Instantpadel\" \/>\n<meta property=\"og:description\" content=\"1 Niet overdekt Instantpadelveld\" \/>\n<meta property=\"og:url\" content=\"https:\/\/instantcourts.com\/instantpadel\/nl\/central-london-alliance-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Instantpadel\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Instantpadel\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-31T11:39:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-31T11:39:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/Central-London-Alliance-Cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1905\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"instantcourts\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"instantcourts\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/nl\\\/central-london-alliance-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/nl\\\/central-london-alliance-2\\\/\"},\"author\":{\"name\":\"instantcourts\",\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/#\\\/schema\\\/person\\\/0ee796dddd76c4b85ee943cb9b8ab809\"},\"headline\":\"Central London Alliance\",\"datePublished\":\"2023-10-31T11:39:35+00:00\",\"dateModified\":\"2023-10-31T11:39:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/nl\\\/central-london-alliance-2\\\/\"},\"wordCount\":6,\"publisher\":{\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/nl\\\/central-london-alliance-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/Central-London-Alliance-Cover.jpg\",\"keywords\":[\"Verenigd Koninkrijk\"],\"articleSection\":[\"Casestudies\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/nl\\\/central-london-alliance-2\\\/\",\"url\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/nl\\\/central-london-alliance-2\\\/\",\"name\":\"Central London Alliance - Instantpadel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/nl\\\/central-london-alliance-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/nl\\\/central-london-alliance-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/Central-London-Alliance-Cover.jpg\",\"datePublished\":\"2023-10-31T11:39:35+00:00\",\"dateModified\":\"2023-10-31T11:39:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/nl\\\/central-london-alliance-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/nl\\\/central-london-alliance-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/nl\\\/central-london-alliance-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/Central-London-Alliance-Cover.jpg\",\"contentUrl\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/Central-London-Alliance-Cover.jpg\",\"width\":1905,\"height\":422},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/nl\\\/central-london-alliance-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Central London Alliance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/#website\",\"url\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/\",\"name\":\"Instantpadel\",\"description\":\"Padel Courts the clever way\",\"publisher\":{\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/#organization\",\"name\":\"Instantpadel\",\"url\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/Instantpadel.webp\",\"contentUrl\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/Instantpadel.webp\",\"width\":2048,\"height\":2048,\"caption\":\"Instantpadel\"},\"image\":{\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Instantpadel\\\/\",\"https:\\\/\\\/www.instagram.com\\\/instantpadel.eu\\\/\",\"https:\\\/\\\/in.linkedin.com\\\/company\\\/instantpadel\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/#\\\/schema\\\/person\\\/0ee796dddd76c4b85ee943cb9b8ab809\",\"name\":\"instantcourts\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f1b4a8dbb6d6e18c4c19f2ea78d2ca1f35ac8badeac8700ff11d1c920eeb1d6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f1b4a8dbb6d6e18c4c19f2ea78d2ca1f35ac8badeac8700ff11d1c920eeb1d6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7f1b4a8dbb6d6e18c4c19f2ea78d2ca1f35ac8badeac8700ff11d1c920eeb1d6?s=96&d=mm&r=g\",\"caption\":\"instantcourts\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Central London Alliance - Instantpadel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/instantcourts.com\/instantpadel\/nl\/central-london-alliance-2\/","og_locale":"en_US","og_type":"article","og_title":"Central London Alliance - Instantpadel","og_description":"1 Niet overdekt Instantpadelveld","og_url":"https:\/\/instantcourts.com\/instantpadel\/nl\/central-london-alliance-2\/","og_site_name":"Instantpadel","article_publisher":"https:\/\/www.facebook.com\/Instantpadel\/","article_published_time":"2023-10-31T11:39:35+00:00","article_modified_time":"2023-10-31T11:39:52+00:00","og_image":[{"width":1905,"height":422,"url":"https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/Central-London-Alliance-Cover.jpg","type":"image\/jpeg"}],"author":"instantcourts","twitter_card":"summary_large_image","twitter_misc":{"Written by":"instantcourts","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/instantcourts.com\/instantpadel\/nl\/central-london-alliance-2\/#article","isPartOf":{"@id":"https:\/\/instantcourts.com\/instantpadel\/nl\/central-london-alliance-2\/"},"author":{"name":"instantcourts","@id":"https:\/\/instantcourts.com\/instantpadel\/#\/schema\/person\/0ee796dddd76c4b85ee943cb9b8ab809"},"headline":"Central London Alliance","datePublished":"2023-10-31T11:39:35+00:00","dateModified":"2023-10-31T11:39:52+00:00","mainEntityOfPage":{"@id":"https:\/\/instantcourts.com\/instantpadel\/nl\/central-london-alliance-2\/"},"wordCount":6,"publisher":{"@id":"https:\/\/instantcourts.com\/instantpadel\/#organization"},"image":{"@id":"https:\/\/instantcourts.com\/instantpadel\/nl\/central-london-alliance-2\/#primaryimage"},"thumbnailUrl":"https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/Central-London-Alliance-Cover.jpg","keywords":["Verenigd Koninkrijk"],"articleSection":["Casestudies"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/instantcourts.com\/instantpadel\/nl\/central-london-alliance-2\/","url":"https:\/\/instantcourts.com\/instantpadel\/nl\/central-london-alliance-2\/","name":"Central London Alliance - Instantpadel","isPartOf":{"@id":"https:\/\/instantcourts.com\/instantpadel\/#website"},"primaryImageOfPage":{"@id":"https:\/\/instantcourts.com\/instantpadel\/nl\/central-london-alliance-2\/#primaryimage"},"image":{"@id":"https:\/\/instantcourts.com\/instantpadel\/nl\/central-london-alliance-2\/#primaryimage"},"thumbnailUrl":"https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/Central-London-Alliance-Cover.jpg","datePublished":"2023-10-31T11:39:35+00:00","dateModified":"2023-10-31T11:39:52+00:00","breadcrumb":{"@id":"https:\/\/instantcourts.com\/instantpadel\/nl\/central-london-alliance-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/instantcourts.com\/instantpadel\/nl\/central-london-alliance-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/instantcourts.com\/instantpadel\/nl\/central-london-alliance-2\/#primaryimage","url":"https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/Central-London-Alliance-Cover.jpg","contentUrl":"https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/Central-London-Alliance-Cover.jpg","width":1905,"height":422},{"@type":"BreadcrumbList","@id":"https:\/\/instantcourts.com\/instantpadel\/nl\/central-london-alliance-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/instantcourts.com\/instantpadel\/"},{"@type":"ListItem","position":2,"name":"Central London Alliance"}]},{"@type":"WebSite","@id":"https:\/\/instantcourts.com\/instantpadel\/#website","url":"https:\/\/instantcourts.com\/instantpadel\/","name":"Instantpadel","description":"Padel Courts the clever way","publisher":{"@id":"https:\/\/instantcourts.com\/instantpadel\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/instantcourts.com\/instantpadel\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/instantcourts.com\/instantpadel\/#organization","name":"Instantpadel","url":"https:\/\/instantcourts.com\/instantpadel\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/instantcourts.com\/instantpadel\/#\/schema\/logo\/image\/","url":"https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/Instantpadel.webp","contentUrl":"https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/Instantpadel.webp","width":2048,"height":2048,"caption":"Instantpadel"},"image":{"@id":"https:\/\/instantcourts.com\/instantpadel\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Instantpadel\/","https:\/\/www.instagram.com\/instantpadel.eu\/","https:\/\/in.linkedin.com\/company\/instantpadel"]},{"@type":"Person","@id":"https:\/\/instantcourts.com\/instantpadel\/#\/schema\/person\/0ee796dddd76c4b85ee943cb9b8ab809","name":"instantcourts","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/7f1b4a8dbb6d6e18c4c19f2ea78d2ca1f35ac8badeac8700ff11d1c920eeb1d6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7f1b4a8dbb6d6e18c4c19f2ea78d2ca1f35ac8badeac8700ff11d1c920eeb1d6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f1b4a8dbb6d6e18c4c19f2ea78d2ca1f35ac8badeac8700ff11d1c920eeb1d6?s=96&d=mm&r=g","caption":"instantcourts"}}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/posts\/8105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/comments?post=8105"}],"version-history":[{"count":2,"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/posts\/8105\/revisions"}],"predecessor-version":[{"id":8108,"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/posts\/8105\/revisions\/8108"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/media\/8101"}],"wp:attachment":[{"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/media?parent=8105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/categories?post=8105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/tags?post=8105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}