{"id":390,"count":2,"description":"","link":"https:\/\/instantcourts.com\/instantpadel\/tag\/usa\/","name":"USA","slug":"usa","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>USA Archives - Instantpadel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/instantcourts.com\/instantpadel\/tag\/usa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"USA Archives - Instantpadel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/instantcourts.com\/instantpadel\/tag\/usa\/\" \/>\n<meta property=\"og:site_name\" content=\"Instantpadel\" \/>\n<meta property=\"og:image\" content=\"https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/cover.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/tag\\\/usa\\\/\",\"url\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/tag\\\/usa\\\/\",\"name\":\"USA Archives - Instantpadel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/tag\\\/usa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/tag\\\/usa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"USA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/#website\",\"url\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/\",\"name\":\"Instantpadel\",\"description\":\"Padel Courts the clever way\",\"publisher\":{\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/#organization\",\"name\":\"Instantpadel\",\"url\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/Instantpadel.webp\",\"contentUrl\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/Instantpadel.webp\",\"width\":2048,\"height\":2048,\"caption\":\"Instantpadel\"},\"image\":{\"@id\":\"https:\\\/\\\/instantcourts.com\\\/instantpadel\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Instantpadel\\\/\",\"https:\\\/\\\/www.instagram.com\\\/instantpadel.eu\\\/\",\"https:\\\/\\\/in.linkedin.com\\\/company\\\/instantpadel\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"USA Archives - Instantpadel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/instantcourts.com\/instantpadel\/tag\/usa\/","og_locale":"en_US","og_type":"article","og_title":"USA Archives - Instantpadel","og_url":"https:\/\/instantcourts.com\/instantpadel\/tag\/usa\/","og_site_name":"Instantpadel","og_image":[{"width":1200,"height":675,"url":"https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/cover.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/instantcourts.com\/instantpadel\/tag\/usa\/","url":"https:\/\/instantcourts.com\/instantpadel\/tag\/usa\/","name":"USA Archives - Instantpadel","isPartOf":{"@id":"https:\/\/instantcourts.com\/instantpadel\/#website"},"breadcrumb":{"@id":"https:\/\/instantcourts.com\/instantpadel\/tag\/usa\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/instantcourts.com\/instantpadel\/tag\/usa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/instantcourts.com\/instantpadel\/"},{"@type":"ListItem","position":2,"name":"USA"}]},{"@type":"WebSite","@id":"https:\/\/instantcourts.com\/instantpadel\/#website","url":"https:\/\/instantcourts.com\/instantpadel\/","name":"Instantpadel","description":"Padel Courts the clever way","publisher":{"@id":"https:\/\/instantcourts.com\/instantpadel\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/instantcourts.com\/instantpadel\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/instantcourts.com\/instantpadel\/#organization","name":"Instantpadel","url":"https:\/\/instantcourts.com\/instantpadel\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/instantcourts.com\/instantpadel\/#\/schema\/logo\/image\/","url":"https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/Instantpadel.webp","contentUrl":"https:\/\/instantcourts.com\/instantpadel\/wp-content\/uploads\/sites\/2\/Instantpadel.webp","width":2048,"height":2048,"caption":"Instantpadel"},"image":{"@id":"https:\/\/instantcourts.com\/instantpadel\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Instantpadel\/","https:\/\/www.instagram.com\/instantpadel.eu\/","https:\/\/in.linkedin.com\/company\/instantpadel"]}]}},"_links":{"self":[{"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/tags\/390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/instantcourts.com\/instantpadel\/wp-json\/wp\/v2\/posts?tags=390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}